{"id":1175,"date":"2013-06-07T13:45:16","date_gmt":"2013-06-07T12:45:16","guid":{"rendered":"https:\/\/www.tallerparentesis.com\/desahuciados\/?p=1175"},"modified":"2019-01-09T09:25:21","modified_gmt":"2019-01-09T08:25:21","slug":"fotos-de-la-presentacion-en-madrid","status":"publish","type":"post","link":"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/","title":{"rendered":"Fotos de la presentaci\u00f3n en Madrid"},"content":{"rendered":"<p>Para ver unas im\u00e1genes de la presentaci\u00f3n en la librer\u00eda La Marabunta, pulse en la imagen:<\/p>\n<p><a href=\"\/\/www.tallerparentesis.com\/gallery\/presentacion-de-desahuciados-en-madrid\/\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-1172\" alt=\"Presentaci\u00f3n de Desahuciados en La Marabunta\" src=\"\/\/www.tallerparentesis.com\/wp-content\/uploads\/2013\/06\/PresentacionDeshauciados_LaMarabunta_627x183.jpg\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para ver unas im\u00e1genes de la presentaci\u00f3n en la librer\u00eda La Marabunta, pulse en la imagen:<\/p>\n","protected":false},"author":127,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fotos de la presentaci\u00f3n en Madrid - Desahuciados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fotos de la presentaci\u00f3n en Madrid - Desahuciados\" \/>\n<meta property=\"og:description\" content=\"Para ver unas im\u00e1genes de la presentaci\u00f3n en la librer\u00eda La Marabunta, pulse en la imagen:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Desahuciados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/tallerparentesismalaga\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-07T12:45:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-09T08:25:21+00:00\" \/>\n<meta property=\"og:image\" content=\"\/\/www.tallerparentesis.com\/wp-content\/uploads\/2013\/06\/PresentacionDeshauciados_LaMarabunta_627x183.jpg\" \/>\n<meta name=\"author\" content=\"Desahuciados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tallerparentsis\" \/>\n<meta name=\"twitter:site\" content=\"@tallerparentsis\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Desahuciados\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/\",\"url\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/\",\"name\":\"Fotos de la presentaci\u00f3n en Madrid - Desahuciados\",\"isPartOf\":{\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#website\"},\"datePublished\":\"2013-06-07T12:45:16+00:00\",\"dateModified\":\"2019-01-09T08:25:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/833505b05c9e90ce0c7373288754d9ac\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotos de la presentaci\u00f3n en Madrid\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#website\",\"url\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/\",\"name\":\"Desahuciados\",\"description\":\"Relatos de la Crisis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/833505b05c9e90ce0c7373288754d9ac\",\"name\":\"Desahuciados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/db593f6c2c9c8141e6db0af88328f30a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/db593f6c2c9c8141e6db0af88328f30a?s=96&d=mm&r=g\",\"caption\":\"Desahuciados\"},\"url\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/author\/desahuciados\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fotos de la presentaci\u00f3n en Madrid - Desahuciados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/","og_locale":"es_ES","og_type":"article","og_title":"Fotos de la presentaci\u00f3n en Madrid - Desahuciados","og_description":"Para ver unas im\u00e1genes de la presentaci\u00f3n en la librer\u00eda La Marabunta, pulse en la imagen:","og_url":"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/","og_site_name":"Desahuciados","article_publisher":"https:\/\/es-es.facebook.com\/tallerparentesismalaga","article_published_time":"2013-06-07T12:45:16+00:00","article_modified_time":"2019-01-09T08:25:21+00:00","og_image":[{"url":"\/\/www.tallerparentesis.com\/wp-content\/uploads\/2013\/06\/PresentacionDeshauciados_LaMarabunta_627x183.jpg"}],"author":"Desahuciados","twitter_card":"summary_large_image","twitter_creator":"@tallerparentsis","twitter_site":"@tallerparentsis","twitter_misc":{"Escrito por":"Desahuciados"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/","url":"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/","name":"Fotos de la presentaci\u00f3n en Madrid - Desahuciados","isPartOf":{"@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#website"},"datePublished":"2013-06-07T12:45:16+00:00","dateModified":"2019-01-09T08:25:21+00:00","author":{"@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/833505b05c9e90ce0c7373288754d9ac"},"breadcrumb":{"@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/fotos-de-la-presentacion-en-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tallerparentesis.com\/desahuciados\/"},{"@type":"ListItem","position":2,"name":"Fotos de la presentaci\u00f3n en Madrid"}]},{"@type":"WebSite","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#website","url":"https:\/\/www.tallerparentesis.com\/desahuciados\/","name":"Desahuciados","description":"Relatos de la Crisis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tallerparentesis.com\/desahuciados\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/833505b05c9e90ce0c7373288754d9ac","name":"Desahuciados","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/db593f6c2c9c8141e6db0af88328f30a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db593f6c2c9c8141e6db0af88328f30a?s=96&d=mm&r=g","caption":"Desahuciados"},"url":"https:\/\/www.tallerparentesis.com\/desahuciados\/author\/desahuciados\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/posts\/1175"}],"collection":[{"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/comments?post=1175"}],"version-history":[{"count":2,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/posts\/1175\/revisions"}],"predecessor-version":[{"id":1177,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/posts\/1175\/revisions\/1177"}],"wp:attachment":[{"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/media?parent=1175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/categories?post=1175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/tags?post=1175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}