{"id":402,"date":"2013-01-05T20:06:44","date_gmt":"2013-01-05T19:06:44","guid":{"rendered":"https:\/\/www.tallerparentesis.com\/desahuciados\/?p=402"},"modified":"2013-01-07T21:28:18","modified_gmt":"2013-01-07T20:28:18","slug":"felicitacion","status":"publish","type":"post","link":"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/","title":{"rendered":"Felicitaci\u00f3n"},"content":{"rendered":"<p>Querido Rafael:<\/p>\n<p style=\"text-align: justify;\">Mi nostalgia se deber\u00e1 a una antigualla, pero aquellas felicitaciones por navidad (tarjetas a todo color con dibujos o fotos o reproducciones de cuadros y paisajes; el sobre a juego; el sello con un ave o un barco o una bandera) requer\u00edan la imaginaci\u00f3n de quienes las enviaban; era una elecci\u00f3n que, en cierto modo, representaba a cada uno de los remitentes. Ahora las felicitaciones son previsibles, peor redactadas y se hacen a trav\u00e9s del correo electr\u00f3nico; de mensajes por el m\u00f3vil, pretendidamente originales y graciosos, que est\u00e1n multiplicados por cientos de miles en todo el pa\u00eds.<br \/>\nLos \u00fanicos<em> christmas<\/em> que todav\u00eda recibimos, en papel satinado y grueso y con su sobre, son el de la empresa que nos hizo una obra en la cocina, el de la compa\u00f1\u00eda de la luz Iberdrola, el de seguros Santa Luc\u00eda o el de la zapater\u00eda Arreglos La Veloz, que es donde nos ponen las medias suelas.<br \/>\nColocadas todas las felicitaciones sobre la c\u00f3moda del sal\u00f3n, abiertas y ordenadas por tama\u00f1os, el mueble parece un expositor de marcas que te desean cosas tan imprecisas como \u00ablo m\u00e1s venturoso para el 2013\u00bb. Tarjetones rubricados por los due\u00f1os o presidentes, cuyas firmas resultan ilegibles en la mayor\u00eda de los casos.<br \/>\nTe comento esto, querido Rafael, porque entre las recibidas me ha conmovido una felicitaci\u00f3n bermellona del banco Santander, amablemente dedicada por don Emilio Bot\u00edn. \u00bfSab\u00eda \u00e9l que el pr\u00f3ximo jueves 17 debo acercarme a la sucursal del barrio para entregar las llaves de la casa que ya no puedo pagar? \u00bfEs un rasgo de humanidad, espont\u00e1neo o madurado, que trata de paliar mi angustia por estar obligado a seguir amortizando las mensualidades de la hipoteca generosamente concedida cuando yo estaba en paro? \u00bfCabe la posibilidad de que me mandara la tarjeta de felicitaci\u00f3n para reutilizarla como un salvoconducto en la sucursal y su director me admita la daci\u00f3n en pago que, si bien me dejar\u00eda igualmente en la calle, permitiese que mi inminente viaje a D\u00fcsseldorf fuera m\u00e1s sosegado y esperanzador?<br \/>\nEn D\u00fcsseldorf me han ofrecido un puesto de camarero en el prestigioso <em>Heinemann Konditorei<\/em>. S\u00e9 que el trabajo nada tiene que ver con mi condici\u00f3n de top\u00f3grafo, pero aqu\u00ed, ya sabes, hay poco que medir. Me pagar\u00e1n 800, y me ceden un piso compartido con otros cuatro ilusionados compatriotas. Fraternizar\u00e9 enseguida; conoces mi car\u00e1cter.<br \/>\nCuando lleguen las pr\u00f3ximas navidades te alegrar\u00e9 con buenas noticias sobre m\u00ed. No esperes que te env\u00ede un destartalado correo electr\u00f3nico, tampoco un mensaje raqu\u00edtico por el m\u00f3vil. Te mandar\u00e9 una felicitaci\u00f3n como las de antes: papel grueso, motivos en relieve, sobre forrado, y buscar\u00e9 un sello donde puedas ver el Rin.<\/p>\n<p>Un abrazo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Querido Rafael: Mi nostalgia se deber\u00e1 a una antigualla, pero aquellas felicitaciones por navidad (tarjetas a todo color con dibujos o fotos o reproducciones de cuadros y paisajes; el sobre a juego; el sello con un ave o un barco &hellip; <a href=\"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Felicitaci\u00f3n - Desahuciados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Felicitaci\u00f3n - Desahuciados\" \/>\n<meta property=\"og:description\" content=\"Querido Rafael: Mi nostalgia se deber\u00e1 a una antigualla, pero aquellas felicitaciones por navidad (tarjetas a todo color con dibujos o fotos o reproducciones de cuadros y paisajes; el sobre a juego; el sello con un ave o un barco &hellip; Sigue leyendo &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Desahuciados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/tallerparentesismalaga\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-05T19:06:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-01-07T20:28:18+00:00\" \/>\n<meta name=\"author\" content=\"Antonio Almansa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tallerparentsis\" \/>\n<meta name=\"twitter:site\" content=\"@tallerparentsis\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Almansa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/\",\"url\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/\",\"name\":\"Felicitaci\u00f3n - Desahuciados\",\"isPartOf\":{\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#website\"},\"datePublished\":\"2013-01-05T19:06:44+00:00\",\"dateModified\":\"2013-01-07T20:28:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/a6513cddf1f207fd6eda63092385ff9c\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Felicitaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#website\",\"url\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/\",\"name\":\"Desahuciados\",\"description\":\"Relatos de la Crisis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/a6513cddf1f207fd6eda63092385ff9c\",\"name\":\"Antonio Almansa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/26cae7099325e1c9fcee51d053c0d514?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/26cae7099325e1c9fcee51d053c0d514?s=96&d=mm&r=g\",\"caption\":\"Antonio Almansa\"},\"description\":\"Fundador del Taller de Escritura Par\u00e9ntesis, en 1988. Ha impartido cursos de escritura creativa en Madrid, Valencia, Vitoria, Oviedo y M\u00e1laga, y ha sido profesor invitado en Buenos Aires (Argentina) y Siena (Italia).\",\"url\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/author\/aalmansa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Felicitaci\u00f3n - Desahuciados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/","og_locale":"es_ES","og_type":"article","og_title":"Felicitaci\u00f3n - Desahuciados","og_description":"Querido Rafael: Mi nostalgia se deber\u00e1 a una antigualla, pero aquellas felicitaciones por navidad (tarjetas a todo color con dibujos o fotos o reproducciones de cuadros y paisajes; el sobre a juego; el sello con un ave o un barco &hellip; Sigue leyendo &rarr;","og_url":"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/","og_site_name":"Desahuciados","article_publisher":"https:\/\/es-es.facebook.com\/tallerparentesismalaga","article_published_time":"2013-01-05T19:06:44+00:00","article_modified_time":"2013-01-07T20:28:18+00:00","author":"Antonio Almansa","twitter_card":"summary_large_image","twitter_creator":"@tallerparentsis","twitter_site":"@tallerparentsis","twitter_misc":{"Escrito por":"Antonio Almansa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/","url":"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/","name":"Felicitaci\u00f3n - Desahuciados","isPartOf":{"@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#website"},"datePublished":"2013-01-05T19:06:44+00:00","dateModified":"2013-01-07T20:28:18+00:00","author":{"@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/a6513cddf1f207fd6eda63092385ff9c"},"breadcrumb":{"@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/felicitacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tallerparentesis.com\/desahuciados\/"},{"@type":"ListItem","position":2,"name":"Felicitaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#website","url":"https:\/\/www.tallerparentesis.com\/desahuciados\/","name":"Desahuciados","description":"Relatos de la Crisis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tallerparentesis.com\/desahuciados\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/a6513cddf1f207fd6eda63092385ff9c","name":"Antonio Almansa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/26cae7099325e1c9fcee51d053c0d514?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/26cae7099325e1c9fcee51d053c0d514?s=96&d=mm&r=g","caption":"Antonio Almansa"},"description":"Fundador del Taller de Escritura Par\u00e9ntesis, en 1988. Ha impartido cursos de escritura creativa en Madrid, Valencia, Vitoria, Oviedo y M\u00e1laga, y ha sido profesor invitado en Buenos Aires (Argentina) y Siena (Italia).","url":"https:\/\/www.tallerparentesis.com\/desahuciados\/author\/aalmansa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/posts\/402"}],"collection":[{"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/comments?post=402"}],"version-history":[{"count":5,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/posts\/402\/revisions"}],"predecessor-version":[{"id":432,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/posts\/402\/revisions\/432"}],"wp:attachment":[{"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/media?parent=402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/categories?post=402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/tags?post=402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}