{"id":770,"date":"2013-02-21T09:11:56","date_gmt":"2013-02-21T08:11:56","guid":{"rendered":"https:\/\/www.tallerparentesis.com\/desahuciados\/?p=770"},"modified":"2016-02-10T21:06:36","modified_gmt":"2016-02-10T20:06:36","slug":"la-vieja-alcancia","status":"publish","type":"post","link":"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/","title":{"rendered":"La vieja alcanc\u00eda"},"content":{"rendered":"<p style=\"text-align: left;\" align=\"center\">de \u00a0Ignacio L\u00f3pez Soriano<\/p>\n<p style=\"text-align: justify;\" align=\"center\">Cuando supo que sus d\u00edas estaban contados, el abuelo Anselmo me regal\u00f3 una gran hucha de barro cocido y me dijo:<\/p>\n<p style=\"text-align: justify;\">\u00a0\u00a0\u00a0\u00a0 \u2212Este tesoro es para ti. Gu\u00e1rdalo en sitio seguro y prom\u00e9teme que solo lo usar\u00e1s cuando no puedas vivir sin \u00e9l. Antes de romper la alcanc\u00eda debes haber agotado todas las dem\u00e1s posibilidades.<\/p>\n<p style=\"text-align: justify;\">As\u00ed jur\u00e9 hacerlo. Por eso, cuando compr\u00e9 la Vespa, esper\u00e9 a tener ahorrado el pu\u00f1ado de pesetas que necesitaba. Lo mismo ocurri\u00f3 cuando quise llevar a la familia a lomos de un \u201cdos caballos\u201d. Para el piso tuve que recurrir a una hipoteca con leoninos intereses que oblig\u00f3 a trabajar incontables horas robadas al sue\u00f1o, a hacer n\u00fameros durante largos a\u00f1os. El tesoro vino muchas veces a la cabeza, pero consigui\u00f3 salvarse.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1314 size-full\" src=\"\/\/www.tallerparentesis.com\/desahuciados\/files\/2013\/02\/alcancia.jpg\" alt=\"vieja alcanc\u00eda\" width=\"455\" height=\"341\" srcset=\"https:\/\/www.tallerparentesis.com\/desahuciados\/files\/2013\/02\/alcancia.jpg 455w, https:\/\/www.tallerparentesis.com\/desahuciados\/files\/2013\/02\/alcancia-300x225.jpg 300w, https:\/\/www.tallerparentesis.com\/desahuciados\/files\/2013\/02\/alcancia-400x300.jpg 400w\" sizes=\"(max-width: 455px) 100vw, 455px\" \/><\/p>\n<p style=\"text-align: justify;\">Ahora, cuando tengo la edad del abuelo Anselmo y pensaba recorrer seguro el camino que me queda, unos personajes trajeados con sueldos indecentes dicen que he vivido por encima de mis posibilidades y condenan a mis hijos y a mis nietos a una existencia que ya cre\u00eda olvidada. Ahora, cuando mi pensi\u00f3n resulta absolutamente insuficiente para levantar el peso de una familia que se ahoga en el paro, he acudido a la vieja alcanc\u00eda. Entre sus trozos de barro solo han aparecido antiguas chapas de cerveza, rancias chapas que colgaron de un salchich\u00f3n\u2026 El abuelo, confiando en m\u00ed, solo me dej\u00f3 el tesoro de una ilusi\u00f3n. \u00c9l tampoco imaginaba que, muchos a\u00f1os despu\u00e9s, algunos vendr\u00edan a hacer a\u00f1icos hasta las m\u00e1s peque\u00f1as ilusiones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>de \u00a0Ignacio L\u00f3pez Soriano Cuando supo que sus d\u00edas estaban contados, el abuelo Anselmo me regal\u00f3 una gran hucha de barro cocido y me dijo: \u00a0\u00a0\u00a0\u00a0 \u2212Este tesoro es para ti. Gu\u00e1rdalo en sitio seguro y prom\u00e9teme que solo lo &hellip; <a href=\"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":127,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La vieja alcanc\u00eda - Desahuciados<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vieja alcanc\u00eda - Desahuciados\" \/>\n<meta property=\"og:description\" content=\"de \u00a0Ignacio L\u00f3pez Soriano Cuando supo que sus d\u00edas estaban contados, el abuelo Anselmo me regal\u00f3 una gran hucha de barro cocido y me dijo: \u00a0\u00a0\u00a0\u00a0 \u2212Este tesoro es para ti. Gu\u00e1rdalo en sitio seguro y prom\u00e9teme que solo lo &hellip; Sigue leyendo &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/\" \/>\n<meta property=\"og:site_name\" content=\"Desahuciados\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-es.facebook.com\/tallerparentesismalaga\" \/>\n<meta property=\"article:published_time\" content=\"2013-02-21T08:11:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-10T20:06:36+00:00\" \/>\n<meta property=\"og:image\" content=\"\/\/www.tallerparentesis.com\/desahuciados\/files\/2013\/02\/alcancia.jpg\" \/>\n<meta name=\"author\" content=\"Desahuciados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@tallerparentsis\" \/>\n<meta name=\"twitter:site\" content=\"@tallerparentsis\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Desahuciados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/\",\"url\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/\",\"name\":\"La vieja alcanc\u00eda - Desahuciados\",\"isPartOf\":{\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#website\"},\"datePublished\":\"2013-02-21T08:11:56+00:00\",\"dateModified\":\"2016-02-10T20:06:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/833505b05c9e90ce0c7373288754d9ac\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vieja alcanc\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#website\",\"url\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/\",\"name\":\"Desahuciados\",\"description\":\"Relatos de la Crisis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/833505b05c9e90ce0c7373288754d9ac\",\"name\":\"Desahuciados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/db593f6c2c9c8141e6db0af88328f30a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/db593f6c2c9c8141e6db0af88328f30a?s=96&d=mm&r=g\",\"caption\":\"Desahuciados\"},\"url\":\"https:\/\/www.tallerparentesis.com\/desahuciados\/author\/desahuciados\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vieja alcanc\u00eda - Desahuciados","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/","og_locale":"es_ES","og_type":"article","og_title":"La vieja alcanc\u00eda - Desahuciados","og_description":"de \u00a0Ignacio L\u00f3pez Soriano Cuando supo que sus d\u00edas estaban contados, el abuelo Anselmo me regal\u00f3 una gran hucha de barro cocido y me dijo: \u00a0\u00a0\u00a0\u00a0 \u2212Este tesoro es para ti. Gu\u00e1rdalo en sitio seguro y prom\u00e9teme que solo lo &hellip; Sigue leyendo &rarr;","og_url":"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/","og_site_name":"Desahuciados","article_publisher":"https:\/\/es-es.facebook.com\/tallerparentesismalaga","article_published_time":"2013-02-21T08:11:56+00:00","article_modified_time":"2016-02-10T20:06:36+00:00","og_image":[{"url":"\/\/www.tallerparentesis.com\/desahuciados\/files\/2013\/02\/alcancia.jpg"}],"author":"Desahuciados","twitter_card":"summary_large_image","twitter_creator":"@tallerparentsis","twitter_site":"@tallerparentsis","twitter_misc":{"Escrito por":"Desahuciados","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/","url":"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/","name":"La vieja alcanc\u00eda - Desahuciados","isPartOf":{"@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#website"},"datePublished":"2013-02-21T08:11:56+00:00","dateModified":"2016-02-10T20:06:36+00:00","author":{"@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/833505b05c9e90ce0c7373288754d9ac"},"breadcrumb":{"@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/la-vieja-alcancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tallerparentesis.com\/desahuciados\/"},{"@type":"ListItem","position":2,"name":"La vieja alcanc\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#website","url":"https:\/\/www.tallerparentesis.com\/desahuciados\/","name":"Desahuciados","description":"Relatos de la Crisis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tallerparentesis.com\/desahuciados\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/833505b05c9e90ce0c7373288754d9ac","name":"Desahuciados","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.tallerparentesis.com\/desahuciados\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/db593f6c2c9c8141e6db0af88328f30a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db593f6c2c9c8141e6db0af88328f30a?s=96&d=mm&r=g","caption":"Desahuciados"},"url":"https:\/\/www.tallerparentesis.com\/desahuciados\/author\/desahuciados\/"}]}},"_links":{"self":[{"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/posts\/770"}],"collection":[{"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/users\/127"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":17,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/posts\/770\/revisions"}],"predecessor-version":[{"id":1315,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/posts\/770\/revisions\/1315"}],"wp:attachment":[{"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/categories?post=770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tallerparentesis.com\/desahuciados\/wp-json\/wp\/v2\/tags?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}